{"id":131,"date":"2019-10-22T15:30:40","date_gmt":"2019-10-22T15:30:40","guid":{"rendered":"https:\/\/rachellebloughltd.com\/blog\/?page_id=131"},"modified":"2019-10-22T15:30:40","modified_gmt":"2019-10-22T15:30:40","slug":"seminar-pre-registration-form","status":"publish","type":"page","link":"https:\/\/rachellebloughltd.com\/blog\/seminar-pre-registration-form\/","title":{"rendered":"Seminar Pre-registration Form"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">If you wish to submit payment by mail you may complete the pre-registration form and then send payment in by check or call me with your credit card information.  You will also be provided an option to submit payment via PayPal after submitting this form.<\/p>\n\n\n\n<div class=\"forminator-guttenberg\"><div class=\"forminator-ui forminator-custom-form forminator-custom-form-129 forminator-design--default  forminator_ajax\" data-forminator-render=\"0\" data-form=\"forminator-module-129\" data-uid=\"6a570a212347a\"><br\/><\/div><form\n\t\t\t\tid=\"forminator-module-129\"\n\t\t\t\tclass=\"forminator-ui forminator-custom-form forminator-custom-form-129 forminator-design--default  forminator_ajax\"\n\t\t\t\tmethod=\"post\"\n\t\t\t\tdata-forminator-render=\"0\"\n\t\t\t\tdata-form-id=\"129\"\n\t\t\t\t data-color-option=\"default\" data-design=\"default\" data-grid=\"open\" style=\"display: none;\"\n\t\t\t\tdata-uid=\"6a570a212347a\"\n\t\t\t><div role=\"alert\" aria-live=\"polite\" class=\"forminator-response-message forminator-error\" aria-hidden=\"true\"><\/div><div class=\"forminator-row\"><div id=\"radio-1\" class=\"forminator-field-radio forminator-col forminator-col-12 \"><div role=\"radiogroup\" class=\"forminator-field\" aria-labelledby=\"forminator-radiogroup-radio-1-6a570a212347a-label\" aria-describedby=\"forminator-radiogroup-radio-1-6a570a212347a-description\"><span id=\"forminator-radiogroup-radio-1-6a570a212347a-label\" class=\"forminator-label\">Select a Seminar<\/span><label id=\"forminator-field-radio-1-label-1\" for=\"forminator-field-radio-1-1-6a570a212347a\" class=\"forminator-radio\" title=\"June 26, 2026, Alzheimer&#039;s Disease and Dementia Care Seminar - Online via Zoom\"><input type=\"radio\" name=\"radio-1\" value=\"January-17,-2023-Alzheimer&#039;s-Disease-and-Dementia-Care-Seminar--\" id=\"forminator-field-radio-1-1-6a570a212347a\" aria-labelledby=\"forminator-field-radio-1-label-1\" data-calculation=\"0\"   aria-describedby=\"forminator-field-radio-1-6a570a212347a-description\"\/><span class=\"forminator-radio-bullet\" aria-hidden=\"true\"><\/span><span class=\"forminator-radio-label\">June 26, 2026, Alzheimer&#8217;s Disease and Dementia Care Seminar &#8211; Online via Zoom<\/span><\/label><label id=\"forminator-field-radio-1-label-2\" for=\"forminator-field-radio-1-2-6a570a212347a\" class=\"forminator-radio\" title=\"July 10, 2026, Alzheimer&#039;s Disease and Dementia Care Seminar -  at New Perspective of Long Grove\"><input type=\"radio\" name=\"radio-1\" value=\"July-10,-2026-at-New-Perspective-of-Long-Grove\" id=\"forminator-field-radio-1-2-6a570a212347a\" aria-labelledby=\"forminator-field-radio-1-label-2\" data-calculation=\"0\"   aria-describedby=\"forminator-field-radio-1-6a570a212347a-description\"\/><span class=\"forminator-radio-bullet\" aria-hidden=\"true\"><\/span><span class=\"forminator-radio-label\">July 10, 2026, Alzheimer&#8217;s Disease and Dementia Care Seminar &#8211;  at New Perspective of Long Grove<\/span><\/label><label id=\"forminator-field-radio-1-label-3\" for=\"forminator-field-radio-1-3-6a570a212347a\" class=\"forminator-radio\" title=\"July 30, 2026, Alzheimer&#039;s Disease and Dementia Care Seminar - Online via Zoom\"><input type=\"radio\" name=\"radio-1\" value=\"July-30,-2026\" id=\"forminator-field-radio-1-3-6a570a212347a\" aria-labelledby=\"forminator-field-radio-1-label-3\" data-calculation=\"0\"   aria-describedby=\"forminator-field-radio-1-6a570a212347a-description\"\/><span class=\"forminator-radio-bullet\" aria-hidden=\"true\"><\/span><span class=\"forminator-radio-label\">July 30, 2026, Alzheimer&#8217;s Disease and Dementia Care Seminar &#8211; Online via Zoom<\/span><\/label><span id=\"forminator-radiogroup-radio-1-6a570a212347a-description\" class=\"forminator-description\">Seminars by Rachelle Blough<\/span><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"html-1\" class=\"forminator-field-html forminator-col forminator-col-12 \"><div class=\"forminator-field forminator-merge-tags\" data-field=\"html-1\"><p>BROCHURE<\/p>\n<p>June 26, 2026 &#8211; <a href=\"https:\/\/rachellebloughltd.com\/blog\/seminars\/NCCDP-ADDC-seminar6-26rblough.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">brochure<\/a><\/p>\n<p>July 10, 2026 &#8211; <a href=\"https:\/\/rachellebloughltd.com\/blog\/seminars\/ADDCseminar-July-10th-2026.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">brochure<\/a><\/p>\n<p>July 30, 2026 &#8211; <a href=\"https:\/\/rachellebloughltd.com\/blog\/seminars\/FINAL-July30th-ADDCseminar-bloughr-online.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">brochure<\/a><\/p><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"name-1\" class=\"forminator-field-name forminator-col forminator-col-12 \"><div class=\"forminator-field\"><label for=\"forminator-field-name-1_6a570a212347a\" id=\"forminator-field-name-1_6a570a212347a-label\" class=\"forminator-label\">Name <span class=\"forminator-required\">*<\/span><\/label><input type=\"text\" name=\"name-1\" value=\"\" placeholder=\"E.g. John Doe\" id=\"forminator-field-name-1_6a570a212347a\" class=\"forminator-input forminator-name--field\" aria-required=\"true\" autocomplete=\"name\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"email-1\" class=\"forminator-field-email forminator-col forminator-col-12 \"><div class=\"forminator-field\"><label for=\"forminator-field-email-1_6a570a212347a\" id=\"forminator-field-email-1_6a570a212347a-label\" class=\"forminator-label\">Email Address <span class=\"forminator-required\">*<\/span><\/label><input type=\"email\" name=\"email-1\" value=\"\" placeholder=\"E.g. john@doe.com\" id=\"forminator-field-email-1_6a570a212347a\" class=\"forminator-input forminator-email--field\" data-required=\"1\" aria-required=\"true\" autocomplete=\"email\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"address-1\" class=\"forminator-field-address forminator-col forminator-col-12 \"><div class=\"forminator-row\"><div id=\"address-1-street_address\" class=\"forminator-col\"><div class=\"forminator-field\"><label for=\"forminator-field-address-1-street_address_6a570a212347a\" id=\"forminator-field-address-1-street_address_6a570a212347a-label\" class=\"forminator-label\">Street Address<\/label><input type=\"text\" name=\"address-1-street_address\" placeholder=\"E.g. 42 Wallaby Way\" id=\"forminator-field-address-1-street_address_6a570a212347a\" class=\"forminator-input\" data-required=\"\" aria-required=\"false\" autocomplete=\"address-line1\" value=\"\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"address-1-address_line\" class=\"forminator-col\"><div class=\"forminator-field\"><label for=\"forminator-field-address-1-address_line_6a570a212347a\" id=\"forminator-field-address-1-address_line_6a570a212347a-label\" class=\"forminator-label\">Apartment, suite, etc<\/label><input type=\"text\" name=\"address-1-address_line\" placeholder=\"\" id=\"forminator-field-address-1-address_line_6a570a212347a\" class=\"forminator-input\" data-required=\"\" aria-required=\"false\" autocomplete=\"address-line2\" value=\"\" \/><\/div><\/div><\/div><div class=\"forminator-row\" data-multiple=\"true\"><div id=\"address-1-city\" class=\"forminator-col forminator-col-6\"><div class=\"forminator-field\"><label for=\"forminator-field-address-1-city_6a570a212347a\" id=\"forminator-field-address-1-city_6a570a212347a-label\" class=\"forminator-label\">City<\/label><input type=\"text\" name=\"address-1-city\" placeholder=\"E.g. Sydney\" id=\"forminator-field-address-1-city_6a570a212347a\" class=\"forminator-input\" data-required=\"\" aria-required=\"false\" autocomplete=\"address-level2\" value=\"\" \/><\/div><\/div><div id=\"address-1-state\" class=\"forminator-col forminator-col-6\"><div class=\"forminator-field\"><label for=\"forminator-field-address-1-state_6a570a212347a\" id=\"forminator-field-address-1-state_6a570a212347a-label\" class=\"forminator-label\">State\/Province<\/label><input type=\"text\" name=\"address-1-state\" placeholder=\"E.g. New South Wales\" id=\"forminator-field-address-1-state_6a570a212347a\" class=\"forminator-input\" data-required=\"\" aria-required=\"false\" autocomplete=\"address-level1\" value=\"\" \/><\/div><\/div><\/div><div class=\"forminator-row\" data-multiple=\"true\"><div id=\"address-1-zip\" class=\"forminator-col forminator-col-6\"><div class=\"forminator-field\"><label for=\"forminator-field-address-1-zip_6a570a212347a\" id=\"forminator-field-address-1-zip_6a570a212347a-label\" class=\"forminator-label\">ZIP \/ Postal Code<\/label><input type=\"text\" name=\"address-1-zip\" placeholder=\"E.g. 2000\" id=\"forminator-field-address-1-zip_6a570a212347a\" class=\"forminator-input\" autocomplete=\"postal-code\" value=\"\" \/><\/div><\/div><div id=\"address-1-country\" class=\"forminator-col forminator-col-6\"><div class=\"forminator-field\"><label for=\"forminator-field-129__field--address-1-country_6a570a212347a\" id=\"forminator-field-129__field--address-1-country_6a570a212347a-label\" class=\"forminator-label\">Country<\/label><select name=\"address-1-country\" id=\"forminator-field-129__field--address-1-country_6a570a212347a\" class=\"forminator-select2\" data-search=\"true\" data-placeholder=\"Select country\" autocomplete=\"country-name\" data-default-value=\"\"><option value=\"\" data-country-code=\"\" selected=\"selected\"><\/option><option value=\"Afghanistan\" data-country-code=\"AF\" >Afghanistan<\/option><option value=\"Albania\" data-country-code=\"AL\" >Albania<\/option><option value=\"Algeria\" data-country-code=\"DZ\" >Algeria<\/option><option value=\"American Samoa\" data-country-code=\"AS\" >American Samoa<\/option><option value=\"Andorra\" data-country-code=\"AD\" >Andorra<\/option><option value=\"Angola\" data-country-code=\"AO\" >Angola<\/option><option value=\"Anguilla\" data-country-code=\"AI\" >Anguilla<\/option><option value=\"Antarctica\" data-country-code=\"AQ\" >Antarctica<\/option><option value=\"Antigua &amp; Barbuda\" data-country-code=\"AG\" >Antigua &amp; Barbuda<\/option><option value=\"Argentina\" data-country-code=\"AR\" >Argentina<\/option><option value=\"Armenia\" data-country-code=\"AM\" >Armenia<\/option><option value=\"Aruba\" data-country-code=\"AW\" >Aruba<\/option><option value=\"Ascension Island\" data-country-code=\"AC\" >Ascension Island<\/option><option value=\"Australia\" data-country-code=\"AU\" >Australia<\/option><option value=\"Austria\" data-country-code=\"AT\" >Austria<\/option><option value=\"Azerbaijan\" data-country-code=\"AZ\" >Azerbaijan<\/option><option value=\"Bahamas\" data-country-code=\"BS\" >Bahamas<\/option><option value=\"Bahrain\" data-country-code=\"BH\" >Bahrain<\/option><option value=\"Bangladesh\" data-country-code=\"BD\" >Bangladesh<\/option><option value=\"Barbados\" data-country-code=\"BB\" >Barbados<\/option><option value=\"Belarus\" data-country-code=\"BY\" >Belarus<\/option><option value=\"Belgium\" data-country-code=\"BE\" >Belgium<\/option><option value=\"Belize\" data-country-code=\"BZ\" >Belize<\/option><option value=\"Benin\" data-country-code=\"BJ\" >Benin<\/option><option value=\"Bermuda\" data-country-code=\"BM\" >Bermuda<\/option><option value=\"Bhutan\" data-country-code=\"BT\" >Bhutan<\/option><option value=\"Bolivia\" data-country-code=\"BO\" >Bolivia<\/option><option value=\"Bosnia and Herzegovina\" data-country-code=\"BA\" >Bosnia and Herzegovina<\/option><option value=\"Botswana\" data-country-code=\"BW\" >Botswana<\/option><option value=\"Bouvet Island\" data-country-code=\"BV\" >Bouvet Island<\/option><option value=\"Brazil\" data-country-code=\"BR\" >Brazil<\/option><option value=\"British Indian Ocean Territory\" data-country-code=\"IO\" >British Indian Ocean Territory<\/option><option value=\"British Virgin Islands\" data-country-code=\"VG\" >British Virgin Islands<\/option><option value=\"Brunei\" data-country-code=\"BN\" >Brunei<\/option><option value=\"Bulgaria\" data-country-code=\"BG\" >Bulgaria<\/option><option value=\"Burkina Faso\" data-country-code=\"BF\" >Burkina Faso<\/option><option value=\"Burundi\" data-country-code=\"BI\" >Burundi<\/option><option value=\"Cabo Verde\" data-country-code=\"CV\" >Cabo Verde<\/option><option value=\"Cambodia\" data-country-code=\"KH\" >Cambodia<\/option><option value=\"Cameroon\" data-country-code=\"CM\" >Cameroon<\/option><option value=\"Canada\" data-country-code=\"CA\" >Canada<\/option><option value=\"Caribbean Netherlands\" data-country-code=\"BQ\" >Caribbean Netherlands<\/option><option value=\"Cayman Islands\" data-country-code=\"KY\" >Cayman Islands<\/option><option value=\"Central African Republic\" data-country-code=\"CF\" >Central African Republic<\/option><option value=\"Chad\" data-country-code=\"TD\" >Chad<\/option><option value=\"Chile\" data-country-code=\"CL\" >Chile<\/option><option value=\"China\" data-country-code=\"CN\" >China<\/option><option value=\"Christmas Island\" data-country-code=\"CX\" >Christmas Island<\/option><option value=\"Cocos Islands\" data-country-code=\"CC\" >Cocos Islands<\/option><option value=\"Colombia\" data-country-code=\"CO\" >Colombia<\/option><option value=\"Comoros\" data-country-code=\"KM\" >Comoros<\/option><option value=\"Congo, Democratic Republic of the\" data-country-code=\"CD\" >Congo, Democratic Republic of the<\/option><option value=\"Congo, Republic of the\" data-country-code=\"CG\" >Congo, Republic of the<\/option><option value=\"Cook Islands\" data-country-code=\"CK\" >Cook Islands<\/option><option value=\"Costa Rica\" data-country-code=\"CR\" >Costa Rica<\/option><option value=\"Croatia\" data-country-code=\"HR\" >Croatia<\/option><option value=\"Cuba\" data-country-code=\"CU\" >Cuba<\/option><option value=\"Cura\u00e7ao\" data-country-code=\"CW\" >Cura\u00e7ao<\/option><option value=\"Cyprus\" data-country-code=\"CY\" >Cyprus<\/option><option value=\"Czechia\" data-country-code=\"CZ\" >Czechia<\/option><option value=\"C\u00f4te d&#039;Ivoire\" data-country-code=\"CI\" >C\u00f4te d&#039;Ivoire<\/option><option value=\"Denmark\" data-country-code=\"DK\" >Denmark<\/option><option value=\"Djibouti\" data-country-code=\"DJ\" >Djibouti<\/option><option value=\"Dominica\" data-country-code=\"DM\" >Dominica<\/option><option value=\"Dominican Republic\" data-country-code=\"DO\" >Dominican Republic<\/option><option value=\"Ecuador\" data-country-code=\"EC\" >Ecuador<\/option><option value=\"Egypt\" data-country-code=\"EG\" >Egypt<\/option><option value=\"El Salvador\" data-country-code=\"SV\" >El Salvador<\/option><option value=\"Equatorial Guinea\" data-country-code=\"GQ\" >Equatorial Guinea<\/option><option value=\"Eritrea\" data-country-code=\"ER\" >Eritrea<\/option><option value=\"Estonia\" data-country-code=\"EE\" >Estonia<\/option><option value=\"Eswatini\" data-country-code=\"SZ\" >Eswatini<\/option><option value=\"Ethiopia\" data-country-code=\"ET\" >Ethiopia<\/option><option value=\"Falkland Islands\" data-country-code=\"FK\" >Falkland Islands<\/option><option value=\"Faroe Islands\" data-country-code=\"FO\" >Faroe Islands<\/option><option value=\"Fiji\" data-country-code=\"FJ\" >Fiji<\/option><option value=\"Finland\" data-country-code=\"FI\" >Finland<\/option><option value=\"France\" data-country-code=\"FR\" >France<\/option><option value=\"French Guiana\" data-country-code=\"GF\" >French Guiana<\/option><option value=\"French Polynesia\" data-country-code=\"PF\" >French Polynesia<\/option><option value=\"French South Territories\" data-country-code=\"TF\" >French South Territories<\/option><option value=\"Gabon\" data-country-code=\"GA\" >Gabon<\/option><option value=\"Gambia\" data-country-code=\"GM\" >Gambia<\/option><option value=\"Georgia\" data-country-code=\"GE\" >Georgia<\/option><option value=\"Germany\" data-country-code=\"DE\" >Germany<\/option><option value=\"Ghana\" data-country-code=\"GH\" >Ghana<\/option><option value=\"Gibraltar\" data-country-code=\"GI\" >Gibraltar<\/option><option value=\"Greece\" data-country-code=\"GR\" >Greece<\/option><option value=\"Greenland\" data-country-code=\"GL\" >Greenland<\/option><option value=\"Grenada\" data-country-code=\"GD\" >Grenada<\/option><option value=\"Guadeloupe\" data-country-code=\"GP\" >Guadeloupe<\/option><option value=\"Guam\" data-country-code=\"GU\" >Guam<\/option><option value=\"Guatemala\" data-country-code=\"GT\" >Guatemala<\/option><option value=\"Guernsey\" data-country-code=\"GG\" >Guernsey<\/option><option value=\"Guinea\" data-country-code=\"GN\" >Guinea<\/option><option value=\"Guinea-Bissau\" data-country-code=\"GW\" >Guinea-Bissau<\/option><option value=\"Guyana\" data-country-code=\"GY\" >Guyana<\/option><option value=\"Haiti\" data-country-code=\"HT\" >Haiti<\/option><option value=\"Heard Island And Mcdonald Island\" data-country-code=\"HM\" >Heard Island And Mcdonald Island<\/option><option value=\"Honduras\" data-country-code=\"HN\" >Honduras<\/option><option value=\"Hong Kong SAR China\" data-country-code=\"HK\" >Hong Kong SAR China<\/option><option value=\"Hungary\" data-country-code=\"HU\" >Hungary<\/option><option value=\"Iceland\" data-country-code=\"IS\" >Iceland<\/option><option value=\"India\" data-country-code=\"IN\" >India<\/option><option value=\"Indonesia\" data-country-code=\"ID\" >Indonesia<\/option><option value=\"Iran\" data-country-code=\"IR\" >Iran<\/option><option value=\"Iraq\" data-country-code=\"IQ\" >Iraq<\/option><option value=\"Ireland\" data-country-code=\"IE\" >Ireland<\/option><option value=\"Isle of Man\" data-country-code=\"IM\" >Isle of Man<\/option><option value=\"Israel\" data-country-code=\"IL\" >Israel<\/option><option value=\"Italy\" data-country-code=\"IT\" >Italy<\/option><option value=\"Jamaica\" data-country-code=\"JM\" >Jamaica<\/option><option value=\"Japan\" data-country-code=\"JP\" >Japan<\/option><option value=\"Jersey\" data-country-code=\"JE\" >Jersey<\/option><option value=\"Jordan\" data-country-code=\"JO\" >Jordan<\/option><option value=\"Kazakhstan\" data-country-code=\"KZ\" >Kazakhstan<\/option><option value=\"Kenya\" data-country-code=\"KE\" >Kenya<\/option><option value=\"Kiribati\" data-country-code=\"KI\" >Kiribati<\/option><option value=\"Kosovo\" data-country-code=\"XK\" >Kosovo<\/option><option value=\"Kuwait\" data-country-code=\"KW\" >Kuwait<\/option><option value=\"Kyrgyzstan\" data-country-code=\"KG\" >Kyrgyzstan<\/option><option value=\"Lao People&#039;s Democratic Republic\" data-country-code=\"LA\" >Lao People&#039;s Democratic Republic<\/option><option value=\"Latvia\" data-country-code=\"LV\" >Latvia<\/option><option value=\"Lebanon\" data-country-code=\"LB\" >Lebanon<\/option><option value=\"Lesotho\" data-country-code=\"LS\" >Lesotho<\/option><option value=\"Liberia\" data-country-code=\"LR\" >Liberia<\/option><option value=\"Libya\" data-country-code=\"LY\" >Libya<\/option><option value=\"Liechtenstein\" data-country-code=\"LI\" >Liechtenstein<\/option><option value=\"Lithuania\" data-country-code=\"LT\" >Lithuania<\/option><option value=\"Luxembourg\" data-country-code=\"LU\" >Luxembourg<\/option><option value=\"Macao SAR China\" data-country-code=\"MO\" >Macao SAR China<\/option><option value=\"Madagascar\" data-country-code=\"MG\" >Madagascar<\/option><option value=\"Malawi\" data-country-code=\"MW\" >Malawi<\/option><option value=\"Malaysia\" data-country-code=\"MY\" >Malaysia<\/option><option value=\"Maldives\" data-country-code=\"MV\" >Maldives<\/option><option value=\"Mali\" data-country-code=\"ML\" >Mali<\/option><option value=\"Malta\" data-country-code=\"MT\" >Malta<\/option><option value=\"Marshall Islands\" data-country-code=\"MH\" >Marshall Islands<\/option><option value=\"Martinique\" data-country-code=\"MQ\" >Martinique<\/option><option value=\"Mauritania\" data-country-code=\"MR\" >Mauritania<\/option><option value=\"Mauritius\" data-country-code=\"MU\" >Mauritius<\/option><option value=\"Mayotte\" data-country-code=\"YT\" >Mayotte<\/option><option value=\"Mexico\" data-country-code=\"MX\" >Mexico<\/option><option value=\"Micronesia\" data-country-code=\"FM\" >Micronesia<\/option><option value=\"Moldova\" data-country-code=\"MD\" >Moldova<\/option><option value=\"Monaco\" data-country-code=\"MC\" >Monaco<\/option><option value=\"Mongolia\" data-country-code=\"MN\" >Mongolia<\/option><option value=\"Montenegro\" data-country-code=\"ME\" >Montenegro<\/option><option value=\"Montserrat\" data-country-code=\"MS\" >Montserrat<\/option><option value=\"Morocco\" data-country-code=\"MA\" >Morocco<\/option><option value=\"Mozambique\" data-country-code=\"MZ\" >Mozambique<\/option><option value=\"Myanmar\" data-country-code=\"MM\" >Myanmar<\/option><option value=\"Namibia\" data-country-code=\"NA\" >Namibia<\/option><option value=\"Nauru\" data-country-code=\"NR\" >Nauru<\/option><option value=\"Nepal\" data-country-code=\"NP\" >Nepal<\/option><option value=\"Netherlands\" data-country-code=\"NL\" >Netherlands<\/option><option value=\"New Caledonia\" data-country-code=\"NC\" >New Caledonia<\/option><option value=\"New Zealand\" data-country-code=\"NZ\" >New Zealand<\/option><option value=\"Nicaragua\" data-country-code=\"NI\" >Nicaragua<\/option><option value=\"Niger\" data-country-code=\"NE\" >Niger<\/option><option value=\"Nigeria\" data-country-code=\"NG\" >Nigeria<\/option><option value=\"Niue\" data-country-code=\"NU\" >Niue<\/option><option value=\"Norfolk Island\" data-country-code=\"NF\" >Norfolk Island<\/option><option value=\"North Korea\" data-country-code=\"KP\" >North Korea<\/option><option value=\"North Macedonia\" data-country-code=\"MK\" >North Macedonia<\/option><option value=\"Northern Mariana Islands\" data-country-code=\"MP\" >Northern Mariana Islands<\/option><option value=\"Norway\" data-country-code=\"NO\" >Norway<\/option><option value=\"Oman\" data-country-code=\"OM\" >Oman<\/option><option value=\"Pakistan\" data-country-code=\"PK\" >Pakistan<\/option><option value=\"Palau\" data-country-code=\"PW\" >Palau<\/option><option value=\"Palestinian Territories\" data-country-code=\"PS\" >Palestinian Territories<\/option><option value=\"Panama\" data-country-code=\"PA\" >Panama<\/option><option value=\"Papua New Guinea\" data-country-code=\"PG\" >Papua New Guinea<\/option><option value=\"Paraguay\" data-country-code=\"PY\" >Paraguay<\/option><option value=\"Peru\" data-country-code=\"PE\" >Peru<\/option><option value=\"Philippines\" data-country-code=\"PH\" >Philippines<\/option><option value=\"Pitcairn Islands\" data-country-code=\"PN\" >Pitcairn Islands<\/option><option value=\"Poland\" data-country-code=\"PL\" >Poland<\/option><option value=\"Portugal\" data-country-code=\"PT\" >Portugal<\/option><option value=\"Puerto Rico\" data-country-code=\"PR\" >Puerto Rico<\/option><option value=\"Qatar\" data-country-code=\"QA\" >Qatar<\/option><option value=\"Romania\" data-country-code=\"RO\" >Romania<\/option><option value=\"Russia\" data-country-code=\"RU\" >Russia<\/option><option value=\"Rwanda\" data-country-code=\"RW\" >Rwanda<\/option><option value=\"R\u00e9union\" data-country-code=\"RE\" >R\u00e9union<\/option><option value=\"Saint Helena\" data-country-code=\"SH\" >Saint Helena<\/option><option value=\"Saint Kitts and Nevis\" data-country-code=\"KN\" >Saint Kitts and Nevis<\/option><option value=\"Saint Lucia\" data-country-code=\"LC\" >Saint Lucia<\/option><option value=\"Saint Vincent and the Grenadines\" data-country-code=\"VC\" >Saint Vincent and the Grenadines<\/option><option value=\"Samoa\" data-country-code=\"WS\" >Samoa<\/option><option value=\"San Marino\" data-country-code=\"SM\" >San Marino<\/option><option value=\"Saudi Arabia\" data-country-code=\"SA\" >Saudi Arabia<\/option><option value=\"Senegal\" data-country-code=\"SN\" >Senegal<\/option><option value=\"Serbia\" data-country-code=\"RS\" >Serbia<\/option><option value=\"Seychelles\" data-country-code=\"SC\" >Seychelles<\/option><option value=\"Sierra Leone\" data-country-code=\"SL\" >Sierra Leone<\/option><option value=\"Singapore\" data-country-code=\"SG\" >Singapore<\/option><option value=\"Sint Maarten\" data-country-code=\"SX\" >Sint Maarten<\/option><option value=\"Slovakia\" data-country-code=\"SK\" >Slovakia<\/option><option value=\"Slovenia\" data-country-code=\"SI\" >Slovenia<\/option><option value=\"Solomon Islands\" data-country-code=\"SB\" >Solomon Islands<\/option><option value=\"Somalia\" data-country-code=\"SO\" >Somalia<\/option><option value=\"South Africa\" data-country-code=\"ZA\" >South Africa<\/option><option value=\"South Georgia and South Sandwich\" data-country-code=\"GS\" >South Georgia and South Sandwich<\/option><option value=\"South Korea\" data-country-code=\"KR\" >South Korea<\/option><option value=\"South Sudan\" data-country-code=\"SS\" >South Sudan<\/option><option value=\"Spain\" data-country-code=\"ES\" >Spain<\/option><option value=\"Sri Lanka\" data-country-code=\"LK\" >Sri Lanka<\/option><option value=\"St. Barth\u00e9lemy\" data-country-code=\"BL\" >St. Barth\u00e9lemy<\/option><option value=\"St. Martin\" data-country-code=\"MF\" >St. Martin<\/option><option value=\"St. Pierre &amp; Miquelon\" data-country-code=\"PM\" >St. Pierre &amp; Miquelon<\/option><option value=\"Sudan\" data-country-code=\"SD\" >Sudan<\/option><option value=\"Suriname\" data-country-code=\"SR\" >Suriname<\/option><option value=\"Svalbard and Jan Mayen\" data-country-code=\"SJ\" >Svalbard and Jan Mayen<\/option><option value=\"Sweden\" data-country-code=\"SE\" >Sweden<\/option><option value=\"Switzerland\" data-country-code=\"CH\" >Switzerland<\/option><option value=\"Syria\" data-country-code=\"SY\" >Syria<\/option><option value=\"S\u00e3o Tom\u00e9 &amp; Pr\u00edncipe\" data-country-code=\"ST\" >S\u00e3o Tom\u00e9 &amp; Pr\u00edncipe<\/option><option value=\"Taiwan\" data-country-code=\"TW\" >Taiwan<\/option><option value=\"Tajikistan\" data-country-code=\"TJ\" >Tajikistan<\/option><option value=\"Tanzania\" data-country-code=\"TZ\" >Tanzania<\/option><option value=\"Thailand\" data-country-code=\"TH\" >Thailand<\/option><option value=\"Timor-Leste\" data-country-code=\"TL\" >Timor-Leste<\/option><option value=\"Togo\" data-country-code=\"TG\" >Togo<\/option><option value=\"Tokelau\" data-country-code=\"TK\" >Tokelau<\/option><option value=\"Tonga\" data-country-code=\"TO\" >Tonga<\/option><option value=\"Trinidad &amp; Tobago\" data-country-code=\"TT\" >Trinidad &amp; Tobago<\/option><option value=\"Tunisia\" data-country-code=\"TN\" >Tunisia<\/option><option value=\"Turkey\" data-country-code=\"TR\" >Turkey<\/option><option value=\"Turkmenistan\" data-country-code=\"TM\" >Turkmenistan<\/option><option value=\"Turks &amp; Caicos Islands\" data-country-code=\"TC\" >Turks &amp; Caicos Islands<\/option><option value=\"Tuvalu\" data-country-code=\"TV\" >Tuvalu<\/option><option value=\"U.S. Virgin Islands\" data-country-code=\"VI\" >U.S. Virgin Islands<\/option><option value=\"US Minor Outlying Islands\" data-country-code=\"UM\" >US Minor Outlying Islands<\/option><option value=\"Uganda\" data-country-code=\"UG\" >Uganda<\/option><option value=\"Ukraine\" data-country-code=\"UA\" >Ukraine<\/option><option value=\"United Arab Emirates\" data-country-code=\"AE\" >United Arab Emirates<\/option><option value=\"United Kingdom\" data-country-code=\"GB\" >United Kingdom<\/option><option value=\"United States of America (USA)\" data-country-code=\"US\" >United States of America (USA)<\/option><option value=\"Uruguay\" data-country-code=\"UY\" >Uruguay<\/option><option value=\"Uzbekistan\" data-country-code=\"UZ\" >Uzbekistan<\/option><option value=\"Vanuatu\" data-country-code=\"VU\" >Vanuatu<\/option><option value=\"Vatican City\" data-country-code=\"VA\" >Vatican City<\/option><option value=\"Venezuela\" data-country-code=\"VE\" >Venezuela<\/option><option value=\"Vietnam\" data-country-code=\"VN\" >Vietnam<\/option><option value=\"Wallis And Futuna Islands\" data-country-code=\"WF\" >Wallis And Futuna Islands<\/option><option value=\"Western Sahara\" data-country-code=\"EH\" >Western Sahara<\/option><option value=\"Yemen\" data-country-code=\"YE\" >Yemen<\/option><option value=\"Zambia\" data-country-code=\"ZM\" >Zambia<\/option><option value=\"Zimbabwe\" data-country-code=\"ZW\" >Zimbabwe<\/option><\/select><\/div><\/div><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"radio-2\" class=\"forminator-field-radio forminator-col forminator-col-12 \"><div role=\"radiogroup\" class=\"forminator-field\" aria-labelledby=\"forminator-radiogroup-radio-2-6a570a212347a-label\"><span id=\"forminator-radiogroup-radio-2-6a570a212347a-label\" class=\"forminator-label\">Do you want CEUs?<\/span><label id=\"forminator-field-radio-2-label-1\" for=\"forminator-field-radio-2-1-6a570a212347a\" class=\"forminator-radio\" title=\"Yes\"><input type=\"radio\" name=\"radio-2\" value=\"yes\" id=\"forminator-field-radio-2-1-6a570a212347a\" aria-labelledby=\"forminator-field-radio-2-label-1\" data-calculation=\"0\"  \/><span class=\"forminator-radio-bullet\" aria-hidden=\"true\"><\/span><span class=\"forminator-radio-label\">Yes<\/span><\/label><label id=\"forminator-field-radio-2-label-2\" for=\"forminator-field-radio-2-2-6a570a212347a\" class=\"forminator-radio\" title=\"No\"><input type=\"radio\" name=\"radio-2\" value=\"no\" id=\"forminator-field-radio-2-2-6a570a212347a\" aria-labelledby=\"forminator-field-radio-2-label-2\" data-calculation=\"0\"  \/><span class=\"forminator-radio-bullet\" aria-hidden=\"true\"><\/span><span class=\"forminator-radio-label\">No<\/span><\/label><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"textarea-1\" class=\"forminator-field-textarea forminator-col forminator-col-12 \"><div class=\"forminator-field\"><label for=\"forminator-field-textarea-1_6a570a212347a\" id=\"forminator-field-textarea-1_6a570a212347a-label\" class=\"forminator-label\">Who Referred You?<\/label><textarea name=\"textarea-1\" placeholder=\"E.g. text placeholder\" id=\"forminator-field-textarea-1_6a570a212347a\" class=\"forminator-textarea\" style=\"--forminator-textarea-min-height:140px;\" ><\/textarea><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"textarea-2\" class=\"forminator-field-textarea forminator-col forminator-col-12 \"><div class=\"forminator-field\"><label for=\"forminator-field-textarea-2_6a570a212347a\" id=\"forminator-field-textarea-2_6a570a212347a-label\" class=\"forminator-label\">Refering individual&#039;s email address:<\/label><textarea name=\"textarea-2\" placeholder=\"E.g. text placeholder\" id=\"forminator-field-textarea-2_6a570a212347a\" class=\"forminator-textarea\" style=\"--forminator-textarea-min-height:140px;\" ><\/textarea><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"captcha-1\" class=\"forminator-field-captcha forminator-col forminator-col-12 \"><div class=\"forminator-captcha-left forminator-g-recaptcha\" data-theme=\"light\"  data-sitekey=\"6Ldi4FsqAAAAANUeKRge5QUm14zhkMk1kDlO7TKO\" data-size=\"normal\"><\/div> <\/div><\/div><input type=\"hidden\" name=\"referer_url\" value=\"\" \/><div class=\"forminator-row forminator-row-last\"><div class=\"forminator-col\"><div class=\"forminator-field\"><button class=\"forminator-button forminator-button-submit\">Send Message<\/button><\/div><\/div><\/div><input type=\"hidden\" id=\"forminator_nonce\" name=\"forminator_nonce\" value=\"d889320380\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/blog\/wp-json\/wp\/v2\/pages\/131\" \/><input type=\"hidden\" name=\"form_id\" value=\"129\"><input type=\"hidden\" name=\"page_id\" value=\"131\"><input type=\"hidden\" name=\"form_type\" value=\"\"><input type=\"hidden\" name=\"current_url\" value=\"https:\/\/rachellebloughltd.com\/blog\/seminar-pre-registration-form\/\"><input type=\"hidden\" name=\"render_id\" value=\"0\"><input type=\"hidden\" name=\"action\" value=\"forminator_submit_form_custom-forms\"><label for=\"input_8\" class=\"forminator-hidden\" aria-hidden=\"true\">Please do not fill in this field. <input id=\"input_8\" type=\"text\" name=\"input_8\" value=\"\" autocomplete=\"off\"><\/label><\/form><\/div>\n","protected":false},"excerpt":{"rendered":"<p>If you wish to submit payment by mail you may complete the pre-registration form and then send payment in by check or call me with your credit card information. You will also be provided an option to submit payment via PayPal after submitting this form.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-131","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rachellebloughltd.com\/blog\/wp-json\/wp\/v2\/pages\/131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rachellebloughltd.com\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rachellebloughltd.com\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rachellebloughltd.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rachellebloughltd.com\/blog\/wp-json\/wp\/v2\/comments?post=131"}],"version-history":[{"count":2,"href":"https:\/\/rachellebloughltd.com\/blog\/wp-json\/wp\/v2\/pages\/131\/revisions"}],"predecessor-version":[{"id":139,"href":"https:\/\/rachellebloughltd.com\/blog\/wp-json\/wp\/v2\/pages\/131\/revisions\/139"}],"wp:attachment":[{"href":"https:\/\/rachellebloughltd.com\/blog\/wp-json\/wp\/v2\/media?parent=131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}